{"id":25579,"date":"2022-10-02T11:32:20","date_gmt":"2022-10-02T11:32:20","guid":{"rendered":"https:\/\/mayahai.org\/?page_id=25579"},"modified":"2022-10-06T15:10:04","modified_gmt":"2022-10-06T15:10:04","slug":"home","status":"publish","type":"page","link":"https:\/\/mayahai.org\/de\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25579\" class=\"elementor elementor-25579\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20fd0e1 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"20fd0e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3571992\" data-id=\"3571992\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2377756 elementor-widget elementor-widget-slider_revolution\" data-id=\"2377756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"home-deutsch-1\" data-id=\"68\" id=\"SR7_68_1\" data-version=\"6.7.53\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_68_1-49\" data-key=\"49\">\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-49-0\" class=\"sr7-layer\">Ma Ya Hai<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-49-5\" class=\"sr7-layer\">Mantra Project for WORLD HEALING with Wei Ling Yi<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-49-21\" class=\"sr7-layer\">Nur unsere Liebe kann die Erde retten.<br \/>10.000 Menschen vereint in einem Herzen &<br \/>einem Mantra f\u00fcr den Weltfrieden<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_68_1-58\" data-key=\"58\">\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-58-3\" class=\"sr7-layer\">Watch<br \/>Trailer<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-58-8\" class=\"sr7-layer\" srscsrc><span class=\"q_font_awsome_icon q_icon_shortcode normal q_font_awsome_icon_holder fa-lg  \" style=\"font-size: 16px;px;color: #FFFFFF; \"data-hover-color=#FFFFFF ><a href=\"https:\/\/www.youtube.com\/c\/YiXueCulture\" target=\"_blank\"><i class=\"fa fa-youtube-play\"><\/i><\/a><\/span><\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-58-9\" class=\"sr7-layer\"><i class=\"pe-7s-bottom-arrow\"><\/i><\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-58-10\" class=\"sr7-layer\" srscsrc><span class=\"q_font_awsome_icon q_icon_shortcode normal q_font_awsome_icon_holder fa-lg  \" style=\"font-size: 16px;px;color: #FFFFFF; \"data-hover-color=#FFFFFF ><a href=\"https:\/\/www.instagram.com\/yixue.cultureofoneness\" target=\"_blank\"><i class=\"fa fa-instagram\"><\/i><\/a><\/span><\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-58-11\" class=\"sr7-layer\" srscsrc><span class=\"q_font_awsome_icon q_icon_shortcode normal q_font_awsome_icon_holder fa-lg  \" style=\"font-size: 16px;px;color: #FFFFFF; \"data-hover-color=#FFFFFF ><a href=\"https:\/\/www.facebook.com\/yixue.de\" target=\"_blank\"><i class=\"fa fa-facebook\"><\/i><\/a><\/span><\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_68_1-58-13\" class=\"sr7-layer\"><i class=\"fa-youtube\"><\/i><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_68_1\"] = {cn:100,state:false,fn: function() { if (window._tpt!==undefined && window._tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_68_1\",el:[900,768,960,720],type:'hero',shdw:'0',gh:[900,768,960,720],gw:[1240,1024,778,480],vpt:['-200px'],size:{fullWidth:true, fullHeight:true},offsetContainer:'',offset:'',mh:'0',onh:0,onw:0,bg:{color:'#ffffff'}});   SR7.PMH[\"SR7_68_1\"].state=true;} else if(SR7.PMH[\"SR7_68_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_68_1\"].fn,19);}};SR7.PMH[\"SR7_68_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6f7341 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"e6f7341\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9caba46\" data-id=\"9caba46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5a7a2f elementor-widget elementor-widget-text-editor\" data-id=\"e5a7a2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span style=\"color: #bb9d5a;\">Ma Ya Hai \u2013 Die Kl\u00e4nge, die das Universum durchstr\u00f6men.<br\/>\nDie Kl\u00e4nge, die Frieden und urspr\u00fcngliche Sch\u00f6nheit zur\u00fcckbringen<br\/>\nf\u00fcr unsere Mutter Erde, die Menschheit und alle Lebewesen.\n<\/span><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de8c370 elementor-widget elementor-widget-text-editor\" data-id=\"de8c370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"color: #bb9d5a;\">WEI LING YI<\/span><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3e1e33 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"a3e1e33\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17158de\" data-id=\"17158de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3b479a elementor-widget elementor-widget-image\" data-id=\"a3b479a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW.jpg\" class=\"attachment-full size-full wp-image-19488\" alt=\"\" srcset=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW.jpg 1024w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-300x300.jpg 300w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-150x150.jpg 150w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-768x768.jpg 768w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-550x550.jpg 550w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-500x500.jpg 500w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-1000x1000.jpg 1000w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-700x700.jpg 700w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/Header_Heart_AdobeStock_239080633_NEW-650x650.jpg 650w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4055ff8\" data-id=\"4055ff8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77fabb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"77fabb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6f873e0\" data-id=\"6f873e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efea471 elementor-widget elementor-widget-text-editor\" data-id=\"efea471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"color: #bb9d5a;\"><span style=\"caret-color: #bb9d5a;\">Willkommen zu diesem\nbesonderen Projekt<br\/>f\u00fcr den\nWeltfrieden<\/span><\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53cf621 elementor-widget elementor-widget-text-editor\" data-id=\"53cf621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">Wir laden Euch ein, gemeinsam mit einem weltweiten Netzwerk von zehntausenden Menschen das kraftvolle Friedens- und Schutzmantra MA YA HAI zu singen, um mitzuhelfen, weltweite Katastrophen und Kriege aufzul\u00f6sen und unserer Mutter Erde Harmonie und Frieden zu schenken. Lasst uns gemeinsam die lichtvollen Schallwellen der Barmherzigkeit und der Heilung auf der Welt verbreiten.<\/h4><p>\u00a0<\/p><h4 style=\"text-align: center;\"><a href=\"#home1\"><span style=\"color: #c1965b;\">Mach mit \u2013 Take the challenge<\/span><\/a><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7857adf elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"7857adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-pulse\" href=\"#home1\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 300 175\" style=\"enable-background:new 0 0 300 175;\" xml:space=\"preserve\"><g>\t<path d=\"M284.3,17.4c8.6,5.6,9.1,10.8,1.8,18.2c-42.1,42.1-84.2,84.2-126.4,126.2c-2.3,2.3-5,4.1-7.5,6.1c-1.5,0-3.1,0-4.6,0  c-2.5-2-5.2-3.9-7.5-6.1c-42-42.1-84.2-84.2-126.3-126.3c-7.3-7.3-6.7-12.8,1.9-18.1c1.5,0,3.1,0,4.6,0c2.8,2.4,5.8,4.6,8.4,7.2  C68.2,64,107.6,103.4,147,142.8c0.9,0.9,1.8,1.7,2.9,2.8c1.2-1.2,2.5-2.3,3.6-3.4c39.4-39.4,78.8-78.8,118.3-118.2  c2.4-2.4,5.2-4.3,7.8-6.5C281.2,17.4,282.8,17.4,284.3,17.4z\"><\/path><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49df646 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"49df646\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f9769b\" data-id=\"8f9769b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4916442 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"4916442\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-53f664e\" data-id=\"53f664e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02c7e55 elementor-widget elementor-widget-menu-anchor\" data-id=\"02c7e55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"home1\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b397abc elementor-widget elementor-widget-text-editor\" data-id=\"b397abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"color: #bb9d5a;\">Ma Ya Hai Mantra Projekt<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-060b876 elementor-widget elementor-widget-text-editor\" data-id=\"060b876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73437c5 elementor-widget elementor-widget-text-editor\" data-id=\"73437c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen.\u00a0<span style=\"letter-spacing: 0px;\">Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen.\u00a0Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen\u00a0<\/span>Menschen<span style=\"letter-spacing: 0px;\">\u00a0und im Kollektiv bewirken kann:\u00a0<\/span><span style=\"background-color: #ffffff;\">Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken.\u00a0<\/span><\/p><p><span style=\"background-color: #ffffff;\">\u00a0<\/span><\/p><p><span style=\"background-color: #ffffff;\">Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten.<\/span><span style=\"letter-spacing: 0px;\">\u00a0Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a40c592 elementor-widget elementor-widget-text-editor\" data-id=\"a40c592\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><span style=\"color: #c1965b;\">Jeder kann mitmachen, jederzeit und \u00fcberall.<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d1b46ff elementor-section-content-middle elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"7d1b46ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/mayahai.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/VID_TrailerMaYaHai_thepath-1.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b8e88f2\" data-id=\"6b8e88f2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-178ed12 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"178ed12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f84aeb0\" data-id=\"f84aeb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77c0db elementor-widget elementor-widget-qi_addons_for_elementor_banner\" data-id=\"77c0db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-banner qodef-layout--standard qodef-vertical--middle qodef-horizontal--left qodef-image--hover-zoom\">\n\t<div class=\"qodef-m-image\">\n\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2.jpg 900w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-300x300.jpg 300w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-150x150.jpg 150w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-768x768.jpg 768w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-550x550.jpg 550w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-500x500.jpg 500w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-700x700.jpg 700w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/09\/IMG_TheMantraJourney_Points_p2-650x650.jpg 650w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div>\n\t<div class=\"qodef-m-content\">\n\t\t<div class=\"qodef-m-content-inner\">\n\t\t\t\t\t\t\t<h5 class=\"qodef-m-title\">\n\t\tWatch Trailer\t<\/h5>\n\t\t\t\t\t\t\t<div class=\"qodef-m-button\">\n\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--textual qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short qodef-text-underline qodef-underline--left\" href=\"https:\/\/youtu.be\/zEZMxX-yscQ\" target=\"_blank\">\t<span class=\"qodef-m-text\"><\/span>\t\t<span class=\"qodef-m-icon\">\t\t<span class=\"qodef-m-icon-inner\">\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\t<\/span><\/a>\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t<a itemprop=\"url\" href=\"https:\/\/youtu.be\/zEZMxX-yscQ\" class=\"qodef-m-banner-link\" target=\"_blank\"><\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-feec27d\" data-id=\"feec27d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3c44da elementor-widget elementor-widget-text-editor\" data-id=\"a3c44da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">T\u00e4glich chanten zehntausende Menschen das Mantra Ma Ya Hai f\u00fcr den Weltfrieden und verbinden sich meditativ mit der Sonnenpyramide in\nTeotihuac\u00e1n in Mexiko.<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d493a56 elementor-widget elementor-widget-text-editor\" data-id=\"d493a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: left;\"><span style=\"color: #ffffff;\">Die Sonnen- und Mondpyramide in Teotihuac\u00e1n Mexiko sind ein zentraler Kraftort der Erde. Hier wurde das Mantra Ma Ya Hai empfangen. Dieser Ort ist ein wichtiger Schl\u00fcssel f\u00fcr die L\u00f6sung der aktuellen Katastrophen und Kriege.<\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-324dd25 elementor-widget__width-auto elementor-widget elementor-widget-qbutton\" data-id=\"324dd25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qbutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/mayahai.org\/mach-mit\" target=\"_blank\" data-hover-background-color='#C1965BC7' data-hover-border-color='#C1965BC7' data-hover-color='#FFFFFF' class=\"qbutton  big_large white qbutton_with_icon\" style=\"border-color: #C1965B; font-weight: 600; font-size: 16px; letter-spacing: 1px; background-color: #C1965B;\">Mach mit!<i class=\"qode_icon_font_awesome fa fa-hand-o-up button_icon custom_icon_size\" style=\"font-size: 18px;\" ><\/i><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-790fdc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"790fdc6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a15a21e\" data-id=\"a15a21e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b5f841 elementor-widget elementor-widget-text-editor\" data-id=\"2b5f841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #bb9d5a;\">Die digitale Ma Ya Hai Reise auf der Yin Ebene<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-457e55c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"457e55c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9f31b9b\" data-id=\"9f31b9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ba81a7 elementor-widget elementor-widget-text-editor\" data-id=\"6ba81a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>W\u00e4hrend dieser kollektiven Bewusstseinsarbeit verbinden wir uns meditativ aus dem Herzen heraus mit zentralen Energieorten der Erde wie Pyramiden und Bergen, die f\u00fcr einen globalen Bewusstseinswandel von entscheidender Bedeutung sind. Dadurch aktivieren wir die ihnen innewohnende regulierende und harmonisierende Kraft. Zugleich empfangen und nutzen wir ihre n\u00e4hrende und heilende Energie. Aktueller Kraftort ist die Gro\u00dfe Sonnenpyramide \u2013 Teotihuac\u00e1n \u2013 Mexiko, wo das Mantra Ma Ya Hai seinen Ursprung hat.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3a0a2f elementor-widget elementor-widget-image\" data-id=\"c3a0a2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mayahai.org\/de\/mach-mit\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mayahai.org\/wp-content\/uploads\/elementor\/thumbs\/Button_Bepart2-pvmvzmlsyru1oq7lds01e0q9xx1fxbbeez2dqcy3f4.jpg\" title=\"Button_Bepart2\" alt=\"Button_Bepart2\" class=\"elementor-animation-pulse\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86e3000 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"86e3000\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2cd0c08\" data-id=\"2cd0c08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f42d2b3 elementor-widget elementor-widget-image\" data-id=\"f42d2b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001.jpg\" class=\"attachment-full size-full wp-image-19912\" alt=\"\" srcset=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001.jpg 1024w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-300x300.jpg 300w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-150x150.jpg 150w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-768x768.jpg 768w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-550x550.jpg 550w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-500x500.jpg 500w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-1000x1000.jpg 1000w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-700x700.jpg 700w, https:\/\/mayahai.org\/wp-content\/uploads\/2022\/08\/SifuAlesStenarEmbracingStone_001-650x650.jpg 650w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c90599c\" data-id=\"c90599c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48a3839 elementor-widget elementor-widget-text-editor\" data-id=\"48a3839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #bb9d5a;\">Wei Ling Yi \u2013 Initiator\ndes<br\/>Ma Ya Hai Mantra Projektes<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-143fe57 elementor-widget elementor-widget-text-editor\" data-id=\"143fe57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Gro\u00dfmeister Wei Ling Yi widmet sein gesamtes Leben der Bewu\u00dftseinsentwicklung der Menschheit. Eine seiner wichtigsten Aufgaben ist die Harmonisierung und Anhebung der universellen Energien auf der kosmischen, irdischen und menschlichen Ebene.\u00a0Aufgrund seines hohen Energie- und Bewusstseinsniveaus ist Wei Ling Yi in der Lage, zielgerichtet und effektiv im Bereich der Informationen zu arbeiten, die sich vor allem auf der Yin-Ebene, der geistigen Ebene, abspielen, die f\u00fcr das menschliche Auge unsichtbar ist.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a58ee24 elementor-widget__width-auto elementor-widget elementor-widget-qbutton\" data-id=\"a58ee24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qbutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/mayahai.org\/de\/wei-ling-yi\/\" target=\"_blank\"  class=\"qbutton  underlined qbutton_with_icon\" style=\"border-color: #000000; \">Read more<span aria-hidden=\"true\" class=\"qode_icon_font_elegant arrow_right-up button_icon\" style=\"\" ><\/span><span class=\"qode-underlined-button-span\" style=\"\"><\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ma Ya Hai \u2013 Die Kl\u00e4nge, die das Universum durchstr\u00f6men. Die Kl\u00e4nge, die Frieden und urspr\u00fcngliche Sch\u00f6nheit zur\u00fcckbringen f\u00fcr unsere Mutter Erde, die Menschheit und alle Lebewesen. WEI LING YI Willkommen zu diesem besonderen Projekt f\u00fcr den Weltfrieden Wir laden Euch ein, gemeinsam mit einem&#8230;<\/p>\n","protected":false},"author":1,"featured_media":26171,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-25579","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Ma Ya Hai \u2013 Global Mantra Project for World Peace<\/title>\n<meta name=\"description\" content=\"Unsere neue Ma Ya Hai Webseite ist online! Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen. F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen. Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen. Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen Menschen und im Kollektiv bewirken kann: Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken. Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten. Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen. Jeder kann mitmachen, jederzeit und \u00fcberall!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mayahai.org\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Ma Ya Hai \u2013 Global Mantra Project for World Peace\" \/>\n<meta property=\"og:description\" content=\"Unsere neue Ma Ya Hai Webseite ist online! Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen. F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen. Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen. Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen Menschen und im Kollektiv bewirken kann: Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken. Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten. Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen. Jeder kann mitmachen, jederzeit und \u00fcberall!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mayahai.org\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma Ya Hai \u2013 Global Mantra Project for World Peace\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yixue.de\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T15:10:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/10\/NL09.2022_HeaderMaYaHai_500.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/\",\"url\":\"https:\\\/\\\/mayahai.org\\\/de\\\/\",\"name\":\"Home - Ma Ya Hai \u2013 Global Mantra Project for World Peace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mayahai.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/NL09.2022_HeaderMaYaHai_500.jpg\",\"datePublished\":\"2022-10-02T11:32:20+00:00\",\"dateModified\":\"2022-10-06T15:10:04+00:00\",\"description\":\"Unsere neue Ma Ya Hai Webseite ist online! Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen. F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen. Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen. Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen Menschen und im Kollektiv bewirken kann: Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken. Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten. Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen. Jeder kann mitmachen, jederzeit und \u00fcberall!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mayahai.org\\\/de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mayahai.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/NL09.2022_HeaderMaYaHai_500.jpg\",\"contentUrl\":\"https:\\\/\\\/mayahai.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/NL09.2022_HeaderMaYaHai_500.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mayahai.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mayahai.org\\\/de\\\/\",\"name\":\"Ma Ya Hai \u2013 Global Mantra Project for World Peace\",\"description\":\"Ma Ya Hai \u2013 Global Mantra Project for World Peace\",\"publisher\":{\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mayahai.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#organization\",\"name\":\"YiXue Bildungszentrum gGmbH\",\"url\":\"https:\\\/\\\/mayahai.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mayahai.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/favicon-32x32-1.png\",\"contentUrl\":\"https:\\\/\\\/mayahai.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/favicon-32x32-1.png\",\"width\":32,\"height\":32,\"caption\":\"YiXue Bildungszentrum gGmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/mayahai.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yixue.de\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/YiXueCulture\",\"https:\\\/\\\/www.instagram.com\\\/yixue.cultureofoneness\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Ma Ya Hai \u2013 Global Mantra Project for World Peace","description":"Unsere neue Ma Ya Hai Webseite ist online! Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen. F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen. Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen. Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen Menschen und im Kollektiv bewirken kann: Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken. Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten. Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen. Jeder kann mitmachen, jederzeit und \u00fcberall!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mayahai.org\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Home - Ma Ya Hai \u2013 Global Mantra Project for World Peace","og_description":"Unsere neue Ma Ya Hai Webseite ist online! Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen. F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen. Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen. Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen Menschen und im Kollektiv bewirken kann: Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken. Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten. Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen. Jeder kann mitmachen, jederzeit und \u00fcberall!","og_url":"https:\/\/mayahai.org\/de\/","og_site_name":"Ma Ya Hai \u2013 Global Mantra Project for World Peace","article_publisher":"https:\/\/www.facebook.com\/yixue.de","article_modified_time":"2022-10-06T15:10:04+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/10\/NL09.2022_HeaderMaYaHai_500.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mayahai.org\/de\/","url":"https:\/\/mayahai.org\/de\/","name":"Home - Ma Ya Hai \u2013 Global Mantra Project for World Peace","isPartOf":{"@id":"https:\/\/mayahai.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mayahai.org\/de\/#primaryimage"},"image":{"@id":"https:\/\/mayahai.org\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/10\/NL09.2022_HeaderMaYaHai_500.jpg","datePublished":"2022-10-02T11:32:20+00:00","dateModified":"2022-10-06T15:10:04+00:00","description":"Unsere neue Ma Ya Hai Webseite ist online! Unser Universum entwickelt sich stetig und durchl\u00e4uft gegenw\u00e4rtig eine gro\u00dfe Wandlungsphase. Wir befinden uns inmitten eines universellen Heilungs- und Transformationsprozesses, der die Erde und die Menschheit auf eine h\u00f6here, neue Bewusstseinsebene f\u00fchrt.An diesem bedeutenden Wendepunkt der Menschheitsgeschichte ruft die weltweite Krise uns auf, an der Entstehung einer neuen Weisheiskultur mitzuwirken. Ein Wandel ist dringend notwendig, denn die Existenz unserer wunderbaren Mutter Erde, der Menschheit und aller Lebewesen ist gef\u00e4hrdet. Wenn wir beginnen, uns wieder mit unserem inneren wahren Selbst, mit der Erde und mit unserem Universum zu verbinden, werden wir gen\u00fcgend Liebe, Kraft und Bewusstsein entwickeln. So k\u00f6nnen wir das Gleichgewicht in uns und die gro\u00dfe Harmonie und Sch\u00f6nheit unserer Mutter Erde erschaffen. F\u00fcr dieses Ziel wurde das MA YA HAI Global Mantra Projekt von Gro\u00dfmeister Wei Ling Yi ins Leben gerufen. Er l\u00e4dt uns ein, ein weltweites Netzwerk von zehntausenden von Menschen aufzubauen. Gemeinsam chanten wir t\u00e4glich das Friedens- und Schutzmantra MA YA HAI im Einklang mit weltweiten Kraft- und Energiepl\u00e4tzen, um ein globales lichtvolles Lotusnetzwerk aufzubauen. Wei Ling Yi hat dieses Mantra im Jahr 2007 auf der Sonnenpyramide in Teotihuac\u00e1n in Mexiko von der geistigen Ebene empfangen. Es hat eine gro\u00dfe transformative Kraft, die heilsame Wirkungen auf der tiefsten Ebene in jedem einzelnen Menschen und im Kollektiv bewirken kann: Das kollektive Singen des Mantras MA YA HAI hat das Potenzial, ein strahlendes, sch\u00fctzendes Qi-Feld aufzubauen. Die kraftvollen und heilenden Energien durchdringen, reinigen und harmonisieren die drei gro\u00dfen Qi-Felder des Himmels, der Erde und des Menschen und lassen sie in ihren nat\u00fcrlichen Zustand zur\u00fcckkehren. Dies wird unvorstellbare positive Ver\u00e4nderungen auf der Erde und in jedem Menschen bewirken. Das MA YA HAI Projekt hat die enorme Kraft, uns zu vereinen, um Katastrophen abzuwenden und Leben zu retten. Es ist ein Projekt, das von allen Mitgliedern der globalen YiXue-Familie geteilt wird. Es ist zu hoffen, dass sich immer mehr Menschen anschlie\u00dfen und es zu einem besonderen Projekt f\u00fcr die gesamte Menschheit machen. Jeder kann mitmachen, jederzeit und \u00fcberall!","breadcrumb":{"@id":"https:\/\/mayahai.org\/de\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mayahai.org\/de\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mayahai.org\/de\/#primaryimage","url":"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/10\/NL09.2022_HeaderMaYaHai_500.jpg","contentUrl":"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/10\/NL09.2022_HeaderMaYaHai_500.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/mayahai.org\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mayahai.org\/de\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/mayahai.org\/de\/#website","url":"https:\/\/mayahai.org\/de\/","name":"Ma Ya Hai \u2013 Global Mantra Project for World Peace","description":"Ma Ya Hai \u2013 Global Mantra Project for World Peace","publisher":{"@id":"https:\/\/mayahai.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mayahai.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mayahai.org\/de\/#organization","name":"YiXue Bildungszentrum gGmbH","url":"https:\/\/mayahai.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mayahai.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/05\/favicon-32x32-1.png","contentUrl":"https:\/\/mayahai.org\/wp-content\/uploads\/2022\/05\/favicon-32x32-1.png","width":32,"height":32,"caption":"YiXue Bildungszentrum gGmbH"},"image":{"@id":"https:\/\/mayahai.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yixue.de","https:\/\/www.youtube.com\/c\/YiXueCulture","https:\/\/www.instagram.com\/yixue.cultureofoneness\/"]}]}},"_links":{"self":[{"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/pages\/25579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/comments?post=25579"}],"version-history":[{"count":168,"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/pages\/25579\/revisions"}],"predecessor-version":[{"id":26176,"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/pages\/25579\/revisions\/26176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/media\/26171"}],"wp:attachment":[{"href":"https:\/\/mayahai.org\/de\/wp-json\/wp\/v2\/media?parent=25579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}